{"id":19349,"date":"2017-07-26T17:00:23","date_gmt":"2017-07-26T20:00:23","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=19349"},"modified":"2017-07-26T17:02:19","modified_gmt":"2017-07-26T20:02:19","slug":"arrancaron-los-entrenamientos-del-sub-15","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/arrancaron-los-entrenamientos-del-sub-15\/","title":{"rendered":"ARRANCARON LOS ENTRENAMIENTOS DEL SUB 15"},"content":{"rendered":"<blockquote><p><strong>En la tarde de este mi\u00e9rcoles se pusieron en marcha los entrenamientos de la Selecci\u00f3n Sub 15. En este sentido, la Liga Mercedina agradece a los dirigentes de Ateneo de la Juventud por permitir desarrollar tal entrenamiento en su campo de deporte.<br \/>\nAl frente de la selecci\u00f3n se encuentran los entrenadores Diego Silvestre y Juan Pablo Vitetta.<\/strong><\/p><\/blockquote>\n<p><a href=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018-1024x576.jpg\" alt=\"\" width=\"860\" height=\"484\" class=\"aligncenter size-large wp-image-19350\" srcset=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018-1024x576.jpg 1024w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018-300x169.jpg 300w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018-768x432.jpg 768w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0018.jpg 1040w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1-1024x576.jpg\" alt=\"\" width=\"860\" height=\"484\" class=\"aligncenter size-large wp-image-19351\" srcset=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1-1024x576.jpg 1024w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1-300x169.jpg 300w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1-768x432.jpg 768w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0019-1.jpg 1040w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1-1024x576.jpg\" alt=\"\" width=\"860\" height=\"484\" class=\"aligncenter size-large wp-image-19353\" srcset=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1-1024x576.jpg 1024w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1-300x169.jpg 300w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1-768x432.jpg 768w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/07\/IMG-20170726-WA0020-1.jpg 1040w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la tarde de este mi\u00e9rcoles se pusieron en marcha los entrenamientos de la Selecci\u00f3n Sub 15. En este sentido, la Liga Mercedina agradece a los dirigentes de Ateneo de la Juventud por permitir desarrollar tal entrenamiento en su campo de deporte. Al frente de la selecci\u00f3n se encuentran los entrenadores Diego Silvestre y Juan Pablo Vitetta.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-19349","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/19349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=19349"}],"version-history":[{"count":2,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/19349\/revisions"}],"predecessor-version":[{"id":19356,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/19349\/revisions\/19356"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=19349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=19349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=19349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}