{"id":18838,"date":"2017-06-09T12:47:50","date_gmt":"2017-06-09T15:47:50","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=18838"},"modified":"2017-06-09T13:39:49","modified_gmt":"2017-06-09T16:39:49","slug":"horarios-para-el-fin-de-semana-126","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/horarios-para-el-fin-de-semana-126\/","title":{"rendered":"HORARIOS PARA EL FIN DE SEMANA"},"content":{"rendered":"<blockquote><p><strong>PRIMERA DIVISION<\/strong><\/p><\/blockquote>\n<p><em><strong>S\u00e1bado 10 de junio, cancha Liga Mercedina<\/strong><\/em><br \/>\n14:00 hs. Estudiantes Vs. Quilmes<br \/>\n16:00 hs. V\u00e9lez Vs. Ateneo<\/p>\n<p><em><strong>Domingo 11 de Junio, cancha Liga Mercedina <\/strong><\/em><br \/>\n13:00 hs. Comunicaciones VS. El Tim\u00f3n<br \/>\n15:00 hs. Palometas Vs. El Front\u00f3n<br \/>\n17:00 hs. Defensores Jrs. VS. Mercedes<\/p>\n<p><em><strong>Domingo 11 de junio cancha Pabell\u00f3n Argentino<\/strong><\/em><br \/>\n15:00 hs. Pabell\u00f3n Argentino Vs. A.M.E.F.I.P. -San Mart\u00edn<\/p>\n<p><em><strong>Domingo 11 de junio, cancha San Marcos<\/strong><\/em><br \/>\n15:30 hs. Atl\u00e9tico Marcos Paz Vs. Juventud<\/p>\n<blockquote><p><strong>RESERVA<\/strong><\/p><\/blockquote>\n<p><em><strong>S\u00e1bado 10 de junio, cancha Comunicaciones<\/strong><\/em><br \/>\n15:00 hs. Comunicaciones VS. El Tim\u00f3n<\/p>\n<p><em><strong>S\u00e1bado 10 de junio, cancha Liga Mercedina<\/strong><\/em><br \/>\n18:00 hs.  Palometas Vs. El Front\u00f3n<\/p>\n<p><em><strong>Domingo 11 de junio, cancha  Ateneo<\/strong><\/em><br \/>\n11:45 hs. Defensores Jrs. VS. Mercedes<br \/>\n13:30 hs. Estudiantes Vs. Quilmes<br \/>\n15:15 hs. V\u00e9lez Vs. Ateneo<\/p>\n<p><em><strong>Domingo 11 de junio, cancha Pabell\u00f3n Argentino<\/strong><\/em><br \/>\n13:15 hs. Pabell\u00f3n Argentino Vs. A.M.E.F.I.P. -San Mart\u00edn<\/p>\n<p><em><strong>S\u00e1bado 10 de junio, cancha Juventud <\/strong><\/em><br \/>\n15:45 hs. Costa Brava Vs. Uni\u00f3n<\/p>\n<p><em><strong>Domingo 11 de junio, cancha San Marcos<\/strong><\/em><br \/>\n13:30 hs. Atl\u00e9tico Marcos Paz Vs. Juventud<\/p>\n<blockquote><p><strong>INFANTIL<\/strong><\/p><\/blockquote>\n<p>Ateneo\tVs. Uni\u00f3n, Estudiantes Vs. Mercedes,  Defensores Vs. El Front\u00f3n, Juventud Vs. Los Vascos<br \/>\nMercedes \u201cA\u201d Vs. Palometas, Quilmes Vs. Comunicaciones<br \/>\n13 hs. Categor\u00eda Promocional<br \/>\n14 hs. Categor\u00eda 2008<br \/>\n15 hs. Categor\u00eda 2007<br \/>\n16 hs. Categor\u00eda 2006<\/p>\n<blockquote><p><strong>JUVENIL<\/strong><\/p><\/blockquote>\n<p>Quilmes Vs. Comunicaciones, Ateneo Vs. Uni\u00f3n, Estudiantes Vs. Mercedes,  Defensores Vs. El Front\u00f3n, V\u00e9lez Sarsfield Vs. Pabell\u00f3n Argentino<br \/>\n11:00 hs. Categor\u00eda 2003<br \/>\n12:15 hs. Categor\u00eda 2004<br \/>\n13:30 hs. Categor\u00eda 2005<br \/>\n14:45 hs. Categor\u00eda 2002<br \/>\n16:00 hs. Categor\u00eda 5<\/p>\n<p>Mercedes \u201cA\u201d Vs. Palometas<br \/>\n11:00 hs. Categor\u00eda 2003<br \/>\n12:15 hs. Categor\u00eda 2004<br \/>\n13:30 hs. Categor\u00eda 2005<br \/>\n14:45 hs. Categor\u00eda 2002<\/p>\n<p>Juventud Vs. Los Vascos<br \/>\n10:45 hs. Categor\u00eda 2003<br \/>\n12:00 hs. Categor\u00eda 2004<br \/>\n13:15 hs. Categor\u00eda 2005<br \/>\n14:30 hs. Categor\u00eda 2002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIMERA DIVISION S\u00e1bado 10 de junio, cancha Liga Mercedina 14:00 hs. Estudiantes Vs. Quilmes 16:00 hs. V\u00e9lez Vs. Ateneo Domingo 11 de Junio, cancha Liga Mercedina 13:00 hs. Comunicaciones VS. El Tim\u00f3n 15:00 hs. Palometas Vs. El Front\u00f3n 17:00 hs. Defensores Jrs. VS. Mercedes Domingo 11 de junio cancha Pabell\u00f3n Argentino 15:00 hs. Pabell\u00f3n Argentino Vs. A.M.E.F.I.P. -San Mart\u00edn Domingo<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18838","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=18838"}],"version-history":[{"count":5,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18838\/revisions"}],"predecessor-version":[{"id":18863,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18838\/revisions\/18863"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=18838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=18838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=18838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}