{"id":18732,"date":"2017-05-25T10:01:43","date_gmt":"2017-05-25T13:01:43","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=18732"},"modified":"2017-05-25T10:01:43","modified_gmt":"2017-05-25T13:01:43","slug":"a-75-anos-de-la-inauguracion-de-nuestra-cancha","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/a-75-anos-de-la-inauguracion-de-nuestra-cancha\/","title":{"rendered":"A 75 A\u00d1OS DE LA INAUGURACION DE NUESTRA CANCHA"},"content":{"rendered":"<p><strong>Un 25 de mayo de 1942 quedaba inaugurada en Mercedes la cancha de la Liga Mercedina. Un recuerdo a la figura del Dr. C\u00e1ndido Espina, quien fuera presidente de nuestra instituci\u00f3n del 20 de junio de 1939 al 28 de abril de 1940 y quien mucho tuvo que ver para que esto se hiciera efectivo.<\/strong><br \/>\n<a href=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/05\/cancha-liga.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/05\/cancha-liga.jpg\" alt=\"cancha liga\" width=\"960\" height=\"539\" class=\"aligncenter size-full wp-image-18733\" srcset=\"https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/05\/cancha-liga.jpg 960w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/05\/cancha-liga-300x168.jpg 300w, https:\/\/ligamercedina.com\/web\/wp-content\/uploads\/2017\/05\/cancha-liga-768x431.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un 25 de mayo de 1942 quedaba inaugurada en Mercedes la cancha de la Liga Mercedina. Un recuerdo a la figura del Dr. C\u00e1ndido Espina, quien fuera presidente de nuestra instituci\u00f3n del 20 de junio de 1939 al 28 de abril de 1940 y quien mucho tuvo que ver para que esto se hiciera efectivo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18732","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=18732"}],"version-history":[{"count":1,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18732\/revisions"}],"predecessor-version":[{"id":18734,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18732\/revisions\/18734"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=18732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=18732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=18732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}