{"id":18613,"date":"2017-05-04T22:14:21","date_gmt":"2017-05-05T01:14:21","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=18613"},"modified":"2017-05-04T22:14:21","modified_gmt":"2017-05-05T01:14:21","slug":"futbol-femenino-sortearon-el-fixture-de-primera-division","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/futbol-femenino-sortearon-el-fixture-de-primera-division\/","title":{"rendered":"FUTBOL FEMENINO: SORTEARON EL FIXTURE DE PRIMERA DIVISION"},"content":{"rendered":"<p>La Liga Mercedina de F\u00fatbol da un paso m\u00e1s en su actividad y en la noche de este jueves en su sede se concret\u00f3 una de las reuniones m\u00e1s importante, ya que qued\u00f3 establecido el programa de partidos para el F\u00fatbol Femenino de Primera Divisi\u00f3n.<br \/>\nSiete ser\u00e1n finalmente las instituciones que tomar\u00e1n intervenci\u00f3n, y el puntapi\u00e9 inicial se dar\u00e1 el pr\u00f3ximo domingo 14 de mayo, en cancha del club Recreativo Uni\u00f3n.<\/p>\n<p>El pr\u00f3ximo jueves se definir\u00e1n los fixtures para las categor\u00edas Sub 13, Sub 15 y Sub 17, donde adem\u00e1s tambi\u00e9n estar\u00e1n participando los clubes Comunicaciones y Alfa de Olivera.<\/p>\n<p>Forma de juego: el Apertura de Primera Divisi\u00f3n se jugar\u00e1 por el sistema de todos contra todos, en partidos de ida. El primero ser\u00e1 el campe\u00f3n. Los encuentros se jugar\u00e1n en cada fecha en una misma cancha. Cada equipo jugar\u00e1 con siete jugadoras en campo y podr\u00e1 contar con hasta ocho suplentes.<br \/>\nLa duraci\u00f3n ser\u00e1 de dos tiempos de 25 minutos cada partido. El valor de las entradas ser\u00e1 de $ 40.-<\/p>\n<p>FIXTURE<\/p>\n<p><em><strong>FECHA 1: Cancha Uni\u00f3n<\/strong><\/em><br \/>\n13 hs. El Front\u00f3n Vs. Club Mercedes<br \/>\n14 hs. Defensores Vs. Envi\u00f3n Mercedes<br \/>\n15 hs. Uni\u00f3n Vs. V\u00e9lez Sarsfield<\/p>\n<p><em><strong>FECHA 2: Cancha Estudiantes<\/strong><\/em><br \/>\nV\u00e9lez S\u00e1rsfield Vs. Defensores<br \/>\nClub Mercedes Vs. Uni\u00f3n<br \/>\nEstudiantes Vs. El Front\u00f3n\t<\/p>\n<p><em><strong>FECHA 3: Cancha Defensores<\/strong><\/em><br \/>\nDefensores Vs. Club Mercedes<br \/>\nEnvi\u00f3n Mercedes Vs. V\u00e9lez Sarsfield<br \/>\nUni\u00f3n Vs. Estudiantes<\/p>\n<p><em><strong>FECHA 4: Cancha El Front\u00f3n<\/strong><\/em><br \/>\nClub Mercedes Vs. Envi\u00f3n Mercedes<br \/>\nEstudiantes Vs. Defensores<br \/>\nEl Front\u00f3n Vs. Uni\u00f3n<\/p>\n<p><em><strong>FECHA 5: Cancha a designar por Envi\u00f3n<\/strong><\/em><br \/>\nDefensores Vs. El Front\u00f3n<br \/>\nEnvi\u00f3n Mercedes Vs. Estudiantes<br \/>\nV\u00e9lez Sarsfield Vs. Club Mercedes<\/p>\n<p><em><strong>FECHA 6: Cancha V\u00e9lez Sarsfield<\/strong><\/em><br \/>\nEstudiantes Vs. V\u00e9lez Sarsfield<br \/>\nEl Front\u00f3n Vs. Envi\u00f3n Mercedes<br \/>\nUni\u00f3n Vs. Defensores<\/p>\n<p><em><strong>FECHA 7: Cancha Mercedes<\/strong><\/em><br \/>\nEnvi\u00f3n Mercedes Vs. Uni\u00f3n<br \/>\nV\u00e9lez Sarsfield Vs. El Front\u00f3n<br \/>\nClub Mercedes Vs. Estudiantes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Liga Mercedina de F\u00fatbol da un paso m\u00e1s en su actividad y en la noche de este jueves en su sede se concret\u00f3 una de las reuniones m\u00e1s importante, ya que qued\u00f3 establecido el programa de partidos para el F\u00fatbol Femenino de Primera Divisi\u00f3n. Siete ser\u00e1n finalmente las instituciones que tomar\u00e1n intervenci\u00f3n, y el puntapi\u00e9 inicial se dar\u00e1 el<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18613","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=18613"}],"version-history":[{"count":1,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18613\/revisions"}],"predecessor-version":[{"id":18614,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/18613\/revisions\/18614"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=18613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=18613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=18613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}