{"id":17886,"date":"2016-12-02T21:01:39","date_gmt":"2016-12-03T00:01:39","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=17886"},"modified":"2016-12-02T21:02:09","modified_gmt":"2016-12-03T00:02:09","slug":"amonestaciones-y-suspensiones","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/amonestaciones-y-suspensiones\/","title":{"rendered":"AMONESTACIONES Y SUSPENSIONES"},"content":{"rendered":"<p>Tras disputarse los Cuartos de Final del Torneo de Primera y dos partidos de Reserva llegaron a la 5a o 10a amonestaci\u00f3n los siguientes jugadores, quienes quedan suspendidos por un (1) partido.<\/p>\n<p>Torre, Marcelo (Comunicaciones)<br \/>\nLucero, Germ\u00e1n (Comunicaciones)<br \/>\nSosa, Joaqu\u00edn (Juventud)<\/p>\n<p>Adem\u00e1s est\u00e1n suspendidos de manera provisional, por haber sido expulsados.<br \/>\nTorres, Franco (Comunicaciones)<br \/>\nAguero, Silvio (AC Comunicaciones)<br \/>\nFar\u00edas, Cristian (Quilmes)<br \/>\nBargiano, Tom\u00e1s (El Front\u00f3n)<br \/>\nMalano, Federico (Quilmes)<\/p>\n<p>Sobre estos \u00faltimos jugadores, se giran los informes al Tribunal de Penas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras disputarse los Cuartos de Final del Torneo de Primera y dos partidos de Reserva llegaron a la 5a o 10a amonestaci\u00f3n los siguientes jugadores, quienes quedan suspendidos por un (1) partido. Torre, Marcelo (Comunicaciones) Lucero, Germ\u00e1n (Comunicaciones) Sosa, Joaqu\u00edn (Juventud) Adem\u00e1s est\u00e1n suspendidos de manera provisional, por haber sido expulsados. Torres, Franco (Comunicaciones) Aguero, Silvio (AC Comunicaciones) Far\u00edas, Cristian<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17886","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=17886"}],"version-history":[{"count":1,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17886\/revisions"}],"predecessor-version":[{"id":17887,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17886\/revisions\/17887"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=17886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=17886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=17886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}