{"id":17842,"date":"2016-11-22T18:57:22","date_gmt":"2016-11-22T21:57:22","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=17842"},"modified":"2016-11-22T18:58:29","modified_gmt":"2016-11-22T21:58:29","slug":"horarios-para-el-fin-de-semana-118","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/horarios-para-el-fin-de-semana-118\/","title":{"rendered":"HORARIOS PARA EL FIN DE SEMANA"},"content":{"rendered":"<blockquote><p><em><strong>PRIMERA DIVISION<\/strong><\/em><\/p><\/blockquote>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha Liga Mercedina<\/strong><\/em><br \/>\n19:15 hs. Comunicaciones Vs. Juventud <\/p>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha Costa Brava<\/strong><\/em><br \/>\n17:00 hs. Costa Brava Vs. Trocha<\/p>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha El Front\u00f3n<\/strong><\/em><br \/>\n17:30 hs. El Front\u00f3n Vs. Mercedes<\/p>\n<p><em><strong>Domingo 27 de noviembre, cancha San Marcos<\/strong><\/em><br \/>\n17:00 hs. San Marcos Vs. Quilmes<\/p>\n<blockquote><p><strong>RESERVA<\/strong><\/p><\/blockquote>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha Liga Mercedina<\/strong><\/em><br \/>\n17:30 hs. Comunicaciones Vs. Juventud <\/p>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha Ateneo<\/strong><\/em><br \/>\n15:30 hs. Estudiantes Vs. V\u00e9lez Sarsfield<br \/>\n17:15 hs. Ateneo Vs. El Tim\u00f3n<\/p>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha Costa Brava<\/strong><\/em><br \/>\n15:00 hs. Costa Brava Vs. Trocha<\/p>\n<p><em><strong>S\u00e1bado 26 de noviembre, cancha El Front\u00f3n<\/strong><\/em><br \/>\n15:30 hs. El Front\u00f3n Vs. Mercedes<\/p>\n<p><em><strong>Domingo 27 de noviembre, cancha San Marcos<\/strong><\/em><br \/>\n15:00 hs. San Marcos Vs. Quilmes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIMERA DIVISION S\u00e1bado 26 de noviembre, cancha Liga Mercedina 19:15 hs. Comunicaciones Vs. Juventud S\u00e1bado 26 de noviembre, cancha Costa Brava 17:00 hs. Costa Brava Vs. Trocha S\u00e1bado 26 de noviembre, cancha El Front\u00f3n 17:30 hs. El Front\u00f3n Vs. Mercedes Domingo 27 de noviembre, cancha San Marcos 17:00 hs. San Marcos Vs. Quilmes RESERVA S\u00e1bado 26 de noviembre, cancha Liga<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17842","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=17842"}],"version-history":[{"count":2,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17842\/revisions"}],"predecessor-version":[{"id":17844,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17842\/revisions\/17844"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=17842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=17842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=17842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}