{"id":17667,"date":"2016-10-13T20:45:26","date_gmt":"2016-10-13T23:45:26","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=17667"},"modified":"2016-10-13T20:45:36","modified_gmt":"2016-10-13T23:45:36","slug":"inconvenientes-electrico","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/inconvenientes-electrico\/","title":{"rendered":"INCONVENIENTES ELECTRICOS"},"content":{"rendered":"<blockquote><p><strong>Se informa que debido a la tormenta que tuvo paso por la ciudad de Mercedes durante la noche del mi\u00e9rcoles y madrugada del jueves, una descarga el\u00e9ctrica produjo da\u00f1os en el sector que abastece energ\u00eda a las torres lindantes al Parque Municipal. Producto de esto, reci\u00e9n este viernes por la ma\u00f1ana se comenzar\u00e1 con el trabajo de reparaci\u00f3n.<\/p>\n<p>Se brinda esta informaci\u00f3n a los fines de interiorizar a los clubes afiliados sobre el inconveniente existente y que podr\u00eda generar alteraciones en la programaci\u00f3n de partidos para el fin de semana.<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Se informa que debido a la tormenta que tuvo paso por la ciudad de Mercedes durante la noche del mi\u00e9rcoles y madrugada del jueves, una descarga el\u00e9ctrica produjo da\u00f1os en el sector que abastece energ\u00eda a las torres lindantes al Parque Municipal. Producto de esto, reci\u00e9n este viernes por la ma\u00f1ana se comenzar\u00e1 con el trabajo de reparaci\u00f3n. Se brinda<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17667","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=17667"}],"version-history":[{"count":2,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17667\/revisions"}],"predecessor-version":[{"id":17669,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17667\/revisions\/17669"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=17667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=17667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=17667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}