{"id":17492,"date":"2016-09-16T18:31:24","date_gmt":"2016-09-16T21:31:24","guid":{"rendered":"https:\/\/ligamercedina.com\/web\/?p=17492"},"modified":"2016-09-18T13:09:53","modified_gmt":"2016-09-18T16:09:53","slug":"tribunal-de-disciplina-fallo-25-2","status":"publish","type":"post","link":"https:\/\/ligamercedina.com\/web\/tribunal-de-disciplina-fallo-25-2\/","title":{"rendered":"TRIBUNAL DE DISCIPLINA: FALLO 25"},"content":{"rendered":"<ul>\n<strong>HONORABLE TRIBUNAL DE PENAS<br \/>\nFALLO N\u00ba 25 \/2016<\/strong><\/ul>\n<p>En la ciudad de Mercedes, Provincia de Buenos Aires, a los 14 de septiembre  de 2016,siendo las 19:00 hs. se re\u00fane el Honorable Tribunal de Penas de la Liga Mercedina de F\u00fatbol, presidido por el Dr. Mat\u00edas Marchesini, con la presencia del Dr. Juan Ignacio Bidone, a fin de tratar los siguientes temas: <\/p>\n<p>1.<br \/>\nCOSTA BRAVA \u2013 SAN MARCOS (1\u00aa Divisi\u00f3n)<br \/>\nMENDEZ, NICOLAS 1 partido de suspensi\u00f3n \u2013 art. 207 del R.T.P.<\/p>\n<p>GERMAN BLANCO  (AC V\u00e9lez)- 1 partidos- art. 184 y 260 del RTP.-<\/p>\n<p>MERCEDES  \u2013 TROCHA (1\u00aa Divisi\u00f3n)<br \/>\nGIACHELLO Ezequiel (Trocha)1 partido de suspensi\u00f3n \u2013 art. 207 del R.T.P.<\/p>\n<p>EL FRONTON VS. TIMON  (1\u00aa Divisi\u00f3n)<br \/>\nDE DIEGO PATRICIO   (TIMON) \u2013 1 partido de suspensi\u00f3n \u2013 art.  207 del RTP.-<br \/>\nBARBIERI PABLO (TIMON)- 4 partidos- art. 185, 207 Del RTP.-<\/p>\n<p>COSTA BRAVA VS. SAN MARCOS(1\u00aa Divisi\u00f3n)<br \/>\nGARCIA, ESTEBAN (COSTA BRAVA) \u2013 1 partido de suspensi\u00f3n \u2013 art. 207 del R.T.P.<\/p>\n<p>VELEZ VS. ATENEO (1\u00aa Divisi\u00f3n)<br \/>\nGUTIERREZ MANUEL (VELEZ)\u2013 3 partidos de suspensi\u00f3n \u2013 art. 200 a)  1 del RTP<br \/>\nLESCANO IVAN (VELEZ) \u2013 2 partidos de suspensi\u00f3n \u2013 art. 200 a)  11 del RTP<br \/>\nDIEGO VILLONE  (AC -) \u2013 1 partido \u2013 art. 186, 260 del RTP <\/p>\n<p>MERCEDES VS. TROCHA (RESERVA)<br \/>\nBLANCO FEDERICO (MERCEDES) \u2013 1 partido \u2013 art. 196 del RTP <\/p>\n<p>COMUNICACIONES VS. QUILMES (9\u00aa Divisi\u00f3n)<br \/>\nTHIAGO NACIMIENTO  (COMU) \u2013 2 partidos \u2013 art. 201 b) 8 del R.T.P.<br \/>\nESPINOZA TOBIAS (QUILMES) \u2013 1 partido \u2013 art. 186 del RTP <\/p>\n<p>VELEZ VS. EL FRONTON (cat. 2003)<br \/>\nALMEIDA LUCAS \u2013 3 partidos \u2013 art. 200 a) 1 del RTP <\/p>\n<p>JUVENTUD VS. UNION (8\u00b0 Divisi\u00f3n)<br \/>\nHERNANDEZ  (JUVENTUD) (Presidente y AC) -2 partidos \u2013 art. 185, 260 del RTP<\/p>\n<p>2.<br \/>\nVISTO: <\/p>\n<p>Ante el reclamo del C.A. QUILMES  y recibido el descargo del JUVENTUD DE SUIPACHA, sobre la circunstancia de la inclusi\u00f3n del jugador Joaqu\u00edn Moyano, categor\u00eda 2000, en el partido reserva y luego en el partido de primera divisi\u00f3n entre los mencionados clubes.-<\/p>\n<p>Tiene dicho el art 107 inciso B, del RTP: P\u00e9rdida de partido cuando el equipo fuera integrado:b) Por jugador menor de dieciocho a\u00f1os de edad que ya hubiera actuado el mismo d\u00eda en otro  partido oficial.-<br \/>\nSe transcribe art. 21 El Tribunal dispondr\u00e1 la devoluci\u00f3n del importe pagado en concepto de Derechos de Protesta \u00fanicamente cuando se pronuncie fallo favorable, en cuyo caso el club al cual le resulte desfavorable el fallo ser\u00e1 sancionado, sin perjuicio de las restantes penas aplicadas, con multa equivalente al Derecho de Protesta de conformidad con lo dispuesto en el art. 14 de este Reglamento. Si no prosperara la protesta el club denunciante abonar\u00e1 a la Liga los gastos que se hubieran originado a ra\u00edz de la misma.<\/p>\n<p>El Tribunal de Penas Resuelve: 1 Que el  Club Costa Brava incurri\u00f3 en falta seg\u00fan el art 107 inciso B, a la P\u00e9rdida del Partido disputado el d\u00eda 21\/08\/2016 frente al club Quilmes, con el siguiente resultado Club Costa Brava 0 &#8211; Club Quilmes 1.-<br \/>\n2 El Tribunal de Penas autoriza a la Liga a reintegrar al Club Quilmes el importe del reclamo respectivo (art. 21 del RTP).-<\/p>\n<p>3.<br \/>\nVisto: en virtud de los distintos informes sobre el partido llevado a cabo el 13 de agosto de 2016, entre Club Mercedes y Club Defensores, categor\u00eda 2003, y el pedido de consideraci\u00f3n planteado por el Club Mercedes; este Tribunal resuelve: No hacer lugar al pedido del CLUB MERCEDES, y mantener lo resuelto en el fallo 22\/2016 (art. 32 y 33 del RTP).- <\/p>\n<p>Visto: lo sucesos ocurridos en el partido de Palometas vs. Los Vascos (Categor\u00eda 2003), donde el club Los Vascos, quedo con menos del m\u00ednimo de jugadores para disputar el encuentro.<br \/>\nTiene dicho el Art. 106 a) que: Perdida del Partido.. e) Cuando un equipo quede en inferioridad num\u00e9rica (menos de siete jugadores), o cuando por cansancio de sus jugadores abandone el juego en cualquier momento del partido.<br \/>\nSe Resuelve: dar por ganado el partido al Club Palometas por 1 a 0 a favor de club mencionado (art. 32, 33 y  106 e) del RTP).-<\/p>\n<p><strong>AGREGADO<\/strong><br \/>\nSe informa que jugados partidos el d\u00eda jueves 15\/9 de 1a Divisi\u00f3n:<\/p>\n<p>4.<br \/>\nTROCHA &#8211; EL FRONTON (1\u00aa Divisi\u00f3n)<br \/>\nSUSPENDER EN FORMA PROVISIONAL A:<br \/>\nLONGOBUCO, Alexis (Trocha)<br \/>\n*** JOEL, Sergio (Trocha)<br \/>\nSTOPIELLO, Germ\u00e1n (DT EL Front\u00f3n)<br \/>\nVALLI, Juan (PF El Front\u00f3n)<br \/>\nTAMPARO, Ezequiel (El Front\u00f3n) &#8211; 1 partido- art. 208 del RTP<br \/>\nDINARDI, Federico (El Front\u00f3n) &#8211; 1 partido- art. 208 del RTP<\/p>\n<p>QUILMES &#8211; ATENEO (1a Divisi\u00f3n)<br \/>\nGROSSO, Federico (Quilmes) &#8211; 1 partido- art. 208 del RTP<\/p>\n<p>*** Se aclara que en el informe de partido se inform\u00f3 como expulsado al jugador Falcone, Lucas, cuando en realidad el expulsado fue Joel, Sergio. Este \u00faltimo suspendido de manera provisional.<\/p>\n<p>Dr. Mat\u00edas Marchesini, Presidente<br \/>\nDr. Juan Ignacio Bidone, Vicepresidente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HONORABLE TRIBUNAL DE PENAS FALLO N\u00ba 25 \/2016 En la ciudad de Mercedes, Provincia de Buenos Aires, a los 14 de septiembre de 2016,siendo las 19:00 hs. se re\u00fane el Honorable Tribunal de Penas de la Liga Mercedina de F\u00fatbol, presidido por el Dr. Mat\u00edas Marchesini, con la presencia del Dr. Juan Ignacio Bidone, a fin de tratar los siguientes<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17492","post","type-post","status-publish","format-standard","hentry","category-informaciongeneral"],"_links":{"self":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/comments?post=17492"}],"version-history":[{"count":3,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17492\/revisions"}],"predecessor-version":[{"id":17510,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/posts\/17492\/revisions\/17510"}],"wp:attachment":[{"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/media?parent=17492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/categories?post=17492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligamercedina.com\/web\/wp-json\/wp\/v2\/tags?post=17492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}